{"id":827,"date":"2022-03-27T11:27:04","date_gmt":"2022-03-27T11:27:04","guid":{"rendered":"https:\/\/departamento.us.es\/ddoe\/master-en-necesidades-educativas-especiales-y-atencion-a-la-diversidad-en-la-escuela-copy\/"},"modified":"2022-03-30T12:36:15","modified_gmt":"2022-03-30T12:36:15","slug":"master-en-formacion-y-orientacion-para-el-trabajo","status":"publish","type":"post","link":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/","title":{"rendered":"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"827\" class=\"elementor elementor-827\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca28956 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca28956\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eda5943\" data-id=\"eda5943\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37192c2 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"37192c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El M\u00e1ster se dirige a personas con inter\u00e9s en especializarse en el estudio, investigaci\u00f3n, gerencia, formaci\u00f3n, orientaci\u00f3n y\/o evaluaci\u00f3n de la formaci\u00f3n para el trabajo en entidades p\u00fablicas y privadas.<\/p><p>Encontrar\u00e1 m\u00e1s informaci\u00f3n del m\u00e1ster explorando la p\u00e1gina institucional de la US o accediendo a la\u00a0<a href=\"http:\/\/fcce.us.es\/estudios-postgrados\" target=\"_blank\" rel=\"noopener\">p\u00e1gina web de la Facultad de Ciencias de la Educaci\u00f3n<\/a>.<\/p><p>Tambi\u00e9n tiene a su disposici\u00f3n el\u00a0<a href=\"http:\/\/webapps.us.es\/fichape\/Doc\/FOLLETO\/folleto_M156.pdf\" target=\"_blank\" rel=\"noopener\">folleto del M\u00e1ster<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d9c61e elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"2d9c61e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/guiadeestudiantes.us.es\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-book\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gu\u00eda de estudiantes<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/educacion.us.es\/estudios\/masteres\/master-en-formacion-y-orientacion-para-el-trabajo\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-list-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Plan de estudios<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El M\u00e1ster se dirige a personas con inter\u00e9s en especializarse en el estudio, investigaci\u00f3n, gerencia, formaci\u00f3n, orientaci\u00f3n y\/o evaluaci\u00f3n de la formaci\u00f3n para el trabajo en entidades p\u00fablicas y privadas. Encontrar\u00e1 m\u00e1s informaci\u00f3n del m\u00e1ster explorando la p\u00e1gina institucional de la US o accediendo a la\u00a0p\u00e1gina web de la Facultad de Ciencias de la Educaci\u00f3n. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-827","post","type-post","status-publish","format-standard","hentry","category-posgrado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo - Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo - Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa\" \/>\n<meta property=\"og:description\" content=\"El M\u00e1ster se dirige a personas con inter\u00e9s en especializarse en el estudio, investigaci\u00f3n, gerencia, formaci\u00f3n, orientaci\u00f3n y\/o evaluaci\u00f3n de la formaci\u00f3n para el trabajo en entidades p\u00fablicas y privadas. Encontrar\u00e1 m\u00e1s informaci\u00f3n del m\u00e1ster explorando la p\u00e1gina institucional de la US o accediendo a la\u00a0p\u00e1gina web de la Facultad de Ciencias de la Educaci\u00f3n. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/FacultaddeCienciasdelaEducacin\/108534009178825\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-27T11:27:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-30T12:36:15+00:00\" \/>\n<meta name=\"author\" content=\"dartigas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EducacionUs\" \/>\n<meta name=\"twitter:site\" content=\"@EducacionUs\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dartigas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/master-en-formacion-y-orientacion-para-el-trabajo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/master-en-formacion-y-orientacion-para-el-trabajo\\\/\"},\"author\":{\"name\":\"dartigas\",\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#\\\/schema\\\/person\\\/73312dbbc57762f107e0ffa04a3c5b8e\"},\"headline\":\"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo\",\"datePublished\":\"2022-03-27T11:27:04+00:00\",\"dateModified\":\"2022-03-30T12:36:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/master-en-formacion-y-orientacion-para-el-trabajo\\\/\"},\"wordCount\":101,\"publisher\":{\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#organization\"},\"articleSection\":[\"Posgrado\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/master-en-formacion-y-orientacion-para-el-trabajo\\\/\",\"url\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/master-en-formacion-y-orientacion-para-el-trabajo\\\/\",\"name\":\"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo - Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#website\"},\"datePublished\":\"2022-03-27T11:27:04+00:00\",\"dateModified\":\"2022-03-30T12:36:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/master-en-formacion-y-orientacion-para-el-trabajo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/master-en-formacion-y-orientacion-para-el-trabajo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/master-en-formacion-y-orientacion-para-el-trabajo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#website\",\"url\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/\",\"name\":\"Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa\",\"description\":\"Universidad de Sevilla\",\"publisher\":{\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#organization\",\"name\":\"Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa\",\"url\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-DOE-US-Ancho320-e1651127401434.png\",\"contentUrl\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo-DOE-US-Ancho320-e1651127401434.png\",\"width\":320,\"height\":110,\"caption\":\"Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa\"},\"image\":{\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/FacultaddeCienciasdelaEducacin\\\/108534009178825\\\/\",\"https:\\\/\\\/x.com\\\/EducacionUs\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/#\\\/schema\\\/person\\\/73312dbbc57762f107e0ffa04a3c5b8e\",\"name\":\"dartigas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ef85687ff0d3d82be312d59cb72f849b0e166ba82ad9eede91d680525fa2f7b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ef85687ff0d3d82be312d59cb72f849b0e166ba82ad9eede91d680525fa2f7b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ef85687ff0d3d82be312d59cb72f849b0e166ba82ad9eede91d680525fa2f7b?s=96&d=mm&r=g\",\"caption\":\"dartigas\"},\"sameAs\":[\"https:\\\/\\\/departamento.us.es\\\/ddoe\"],\"url\":\"https:\\\/\\\/departamento.us.es\\\/ddoe\\\/author\\\/dartigas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo - Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo - Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa","og_description":"El M\u00e1ster se dirige a personas con inter\u00e9s en especializarse en el estudio, investigaci\u00f3n, gerencia, formaci\u00f3n, orientaci\u00f3n y\/o evaluaci\u00f3n de la formaci\u00f3n para el trabajo en entidades p\u00fablicas y privadas. Encontrar\u00e1 m\u00e1s informaci\u00f3n del m\u00e1ster explorando la p\u00e1gina institucional de la US o accediendo a la\u00a0p\u00e1gina web de la Facultad de Ciencias de la Educaci\u00f3n. [&hellip;]","og_url":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/","og_site_name":"Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa","article_publisher":"https:\/\/www.facebook.com\/pages\/FacultaddeCienciasdelaEducacin\/108534009178825\/","article_published_time":"2022-03-27T11:27:04+00:00","article_modified_time":"2022-03-30T12:36:15+00:00","author":"dartigas","twitter_card":"summary_large_image","twitter_creator":"@EducacionUs","twitter_site":"@EducacionUs","twitter_misc":{"Escrito por":"dartigas","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/#article","isPartOf":{"@id":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/"},"author":{"name":"dartigas","@id":"https:\/\/departamento.us.es\/ddoe\/#\/schema\/person\/73312dbbc57762f107e0ffa04a3c5b8e"},"headline":"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo","datePublished":"2022-03-27T11:27:04+00:00","dateModified":"2022-03-30T12:36:15+00:00","mainEntityOfPage":{"@id":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/"},"wordCount":101,"publisher":{"@id":"https:\/\/departamento.us.es\/ddoe\/#organization"},"articleSection":["Posgrado"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/","url":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/","name":"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo - Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa","isPartOf":{"@id":"https:\/\/departamento.us.es\/ddoe\/#website"},"datePublished":"2022-03-27T11:27:04+00:00","dateModified":"2022-03-30T12:36:15+00:00","breadcrumb":{"@id":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/departamento.us.es\/ddoe\/master-en-formacion-y-orientacion-para-el-trabajo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/departamento.us.es\/ddoe\/"},{"@type":"ListItem","position":2,"name":"M\u00e1ster en Formaci\u00f3n y Orientaci\u00f3n para el trabajo"}]},{"@type":"WebSite","@id":"https:\/\/departamento.us.es\/ddoe\/#website","url":"https:\/\/departamento.us.es\/ddoe\/","name":"Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa","description":"Universidad de Sevilla","publisher":{"@id":"https:\/\/departamento.us.es\/ddoe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/departamento.us.es\/ddoe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/departamento.us.es\/ddoe\/#organization","name":"Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa","url":"https:\/\/departamento.us.es\/ddoe\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/departamento.us.es\/ddoe\/#\/schema\/logo\/image\/","url":"https:\/\/departamento.us.es\/ddoe\/wp-content\/uploads\/2022\/04\/Logo-DOE-US-Ancho320-e1651127401434.png","contentUrl":"https:\/\/departamento.us.es\/ddoe\/wp-content\/uploads\/2022\/04\/Logo-DOE-US-Ancho320-e1651127401434.png","width":320,"height":110,"caption":"Departamento de Did\u00e1ctica y Organizaci\u00f3n Educativa"},"image":{"@id":"https:\/\/departamento.us.es\/ddoe\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/FacultaddeCienciasdelaEducacin\/108534009178825\/","https:\/\/x.com\/EducacionUs"]},{"@type":"Person","@id":"https:\/\/departamento.us.es\/ddoe\/#\/schema\/person\/73312dbbc57762f107e0ffa04a3c5b8e","name":"dartigas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2ef85687ff0d3d82be312d59cb72f849b0e166ba82ad9eede91d680525fa2f7b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ef85687ff0d3d82be312d59cb72f849b0e166ba82ad9eede91d680525fa2f7b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ef85687ff0d3d82be312d59cb72f849b0e166ba82ad9eede91d680525fa2f7b?s=96&d=mm&r=g","caption":"dartigas"},"sameAs":["https:\/\/departamento.us.es\/ddoe"],"url":"https:\/\/departamento.us.es\/ddoe\/author\/dartigas\/"}]}},"_links":{"self":[{"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/posts\/827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/comments?post=827"}],"version-history":[{"count":0,"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/posts\/827\/revisions"}],"wp:attachment":[{"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/media?parent=827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/categories?post=827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/departamento.us.es\/ddoe\/wp-json\/wp\/v2\/tags?post=827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}